{"id":3913,"date":"2023-12-01T16:12:37","date_gmt":"2023-12-01T14:12:37","guid":{"rendered":"https:\/\/ordilu.com\/?post_type=product&#038;p=3913"},"modified":"2026-04-03T21:22:13","modified_gmt":"2026-04-03T19:22:13","slug":"alpina-al-525gs4aq6b-alpiner-4-automatik","status":"publish","type":"product","link":"https:\/\/ordilu.com\/de\/product\/alpina-al-525gs4aq6b-alpiner-4-automatic\/","title":{"rendered":"Alpina AL-525GS4AQ6B Alpiner 4 Automatik"},"content":{"rendered":"<p>Alpina, gegr\u00fcndet 1883 und ber\u00fchmt f\u00fcr ihr charakteristisches rotes Dreieck, ist eine renommierte Uhrenmanufaktur mit Sitz in Genf, Schweiz, und einer mehr als 135-j\u00e4hrigen Geschichte.<\/p>\n<p>Als wahrer Pionier der Schweizer Uhrenindustrie hat Alpina zahlreiche Patente angemeldet und innovative Uhrwerke entwickelt. Mit der Entwicklung der legend\u00e4ren Alpina 4 im Jahr 1938 erfand Alpina das Konzept der Schweizer Sportuhr, wie wir sie heute kennen.<\/p>\n<div style=\"max-width: 810px; margin: 0 auto; overflow: hidden; text-align: center;\">\n  <div style=\"width: 405px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-3913-1\" width=\"405\" height=\"540\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/ordilu.com\/wp-content\/uploads\/2023\/12\/4519e47239e64fc297c3af26fdbec333.HD-1080p-7.2Mbps-12709019.mp4?_=1\" \/><a href=\"https:\/\/ordilu.com\/wp-content\/uploads\/2023\/12\/4519e47239e64fc297c3af26fdbec333.HD-1080p-7.2Mbps-12709019.mp4\">https:\/\/ordilu.com\/wp-content\/uploads\/2023\/12\/4519e47239e64fc297c3af26fdbec333.HD-1080p-7.2Mbps-12709019.mp4<\/a><\/video><\/div><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p><strong>\u2713<\/strong> Alpina 2 year manufacturer&#8217;s warranty<br \/>\n<strong>\u2713<\/strong>\u00a0Kostenlose Geschenkverpackung<br \/>\n<strong>\u2713<\/strong>\u00a0<a href=\"https:\/\/ordilu.com\/de\/free-watch-band-shortening\/\" data-type=\"URL\" data-id=\"https:\/\/ordilu.com\/free-watch-band-shortening\/\">Kostenloses K\u00fcrzen des Uhrenarmbands<\/a><br \/>\n<strong>\u2713\u00a0<\/strong>30-t\u00e4giges R\u00fcckgaberecht<br \/>\n<strong>\u2713\u00a0<\/strong>Schneller und kostenloser versicherter Versand<br \/>\n<strong>\u2713<\/strong>\u00a0Professioneller Kundenservice ist 7 Tage die Woche verf\u00fcgbar.<\/p>\n<p>Diese Alpina-Uhr besitzt ein 40-mm-Edelstahlgeh\u00e4use mit einem in der Schweiz gefertigten Automatikwerk Al-525. Sie ist mit einem Edelstahlarmband ausgestattet und bis 10 ATM wasserdicht.<\/p>\n<p>Die Uhr wird mit einer 2-j\u00e4hrigen Herstellergarantie geliefert.<\/p>","protected":false},"featured_media":8308,"template":"","meta":[],"product_brand":[],"product_cat":[161],"product_tag":[416],"class_list":["post-3913","product","type-product","status-publish","has-post-thumbnail","product_cat-alpina","product_tag-ts","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/product\/3913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/media\/8308"}],"wp:attachment":[{"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/media?parent=3913"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/product_brand?post=3913"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/product_cat?post=3913"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ordilu.com\/de\/wp-json\/wp\/v2\/product_tag?post=3913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}