{"id":15296,"date":"2026-02-10T22:15:57","date_gmt":"2026-02-10T20:15:57","guid":{"rendered":"https:\/\/ordilu.com\/?post_type=product&#038;p=15296"},"modified":"2026-04-03T21:20:35","modified_gmt":"2026-04-03T19:20:35","slug":"cronografo-luminox-xs-3583-nd-navy-seal","status":"publish","type":"product","link":"https:\/\/ordilu.com\/co\/product\/luminox-xs-3583-nd-navy-seal-chronograph\/","title":{"rendered":"Cron\u00f3grafo Luminox XS.3583.ND Navy Seal"},"content":{"rendered":"<p>Luminox, la marca original de relojes luminosos autoalimentados, es la elecci\u00f3n predilecta de los SEAL de la Marina de los EE. UU., los pilotos del avi\u00f3n furtivo F-117 Nighthawk\u2122 y otras fuerzas de \u00e9lite. Los relojes Luminox brillan 100 veces m\u00e1s que la mayor\u00eda de los relojes luminosos, lo que les confiere una legibilidad superior. Resistentes, potentes y precisos, los relojes Luminox de fabricaci\u00f3n suiza son el equipo de visi\u00f3n nocturna definitivo para atletas de alto rendimiento, aventureros y otros profesionales de \u00e9lite.<\/p>\n<p>La serie 3580 del cron\u00f3grafo Luminox es la \u00faltima evoluci\u00f3n de la exitosa colecci\u00f3n de relojes Luminox. Compuesta por cinco modelos, la serie incorpora varias novedades interesantes, como la funci\u00f3n de cron\u00f3grafo y la caja de CARBONOX\u2122.<\/p>","protected":false},"excerpt":{"rendered":"<p><strong>\u2713<\/strong> Garant\u00eda del fabricante de 2 a\u00f1os para el modelo Luminox<br \/>\n<strong>\u2713<\/strong>\u00a0Envoltura de regalo gratuita<br \/>\n<strong>\u2713<\/strong>\u00a0<a href=\"https:\/\/ordilu.com\/co\/free-watch-band-shortening\/\" data-type=\"URL\" data-id=\"https:\/\/ordilu.com\/free-watch-band-shortening\/\">Acortamiento de correa de reloj gratuito<\/a><br \/>\n<strong>\u2713\u00a0<\/strong>Pol\u00edtica de devoluciones de 30 d\u00edas<br \/>\n<strong>\u2713\u00a0<\/strong>Env\u00edo r\u00e1pido y gratuito con seguro<br \/>\n<strong>\u2713<\/strong>\u00a0Servicio de atenci\u00f3n al cliente profesional disponible los 7 d\u00edas de la semana.<\/p>\n<p>Este reloj Luminox cuenta con una caja de Carbonox de 45 mm que alberga un movimiento de cuarzo de fabricaci\u00f3n suiza. El reloj est\u00e1 equipado con una correa textil y es resistente al agua hasta 20 ATM.<\/p>\n<p>El reloj incluye una garant\u00eda del fabricante de 2 a\u00f1os.<\/p>","protected":false},"featured_media":15299,"template":"","meta":[],"product_brand":[],"product_cat":[364],"product_tag":[416],"class_list":["post-15296","product","type-product","status-publish","has-post-thumbnail","product_cat-luminox","product_tag-ts","pa_ean-789","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/product\/15296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/media\/15299"}],"wp:attachment":[{"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/media?parent=15296"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/product_brand?post=15296"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/product_cat?post=15296"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ordilu.com\/co\/wp-json\/wp\/v2\/product_tag?post=15296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}